{"id":1096,"date":"2018-08-31T16:45:22","date_gmt":"2018-08-31T14:45:22","guid":{"rendered":"https:\/\/consbelohorizonte.esteri.it\/news\/dal_consolato\/2018\/08\/missione-del-funzionario-itinerante_3\/"},"modified":"2018-08-31T16:45:22","modified_gmt":"2018-08-31T14:45:22","slug":"missione-del-funzionario-itinerante_3","status":"publish","type":"post","link":"https:\/\/consbelohorizonte.esteri.it\/it\/news\/dal_consolato\/2018\/08\/missione-del-funzionario-itinerante_3\/","title":{"rendered":"MISSIONE DEL FUNZIONARIO ITINERANTE PASSAPORTI A PO\u00c7OS DE CALDAS (10-11 OTTOBRE 2018)"},"content":{"rendered":"<p>Nel tentativo di agevolare coloro per cui \u00e8 pi\u00f9 difficoltoso raggiungere il Consolato a Belo Horizonte, continuiamo le missioni di un \u201cfunzionario itinerante\u201d, che raccoglier\u00e0 le impronte digitali dei cittadini e delle cittadine italiani\/e interessati a richiedere un libretto di passaporto.<\/p>\n<p style=\"text-align: justify;\">I libretti, stampati successivamente, saranno trasmessi via posta ai rispettivi titolari (previa consegna al funzionario itinerante di una busta pre-affrancata per carta registrada per ogni richiedente, con le caratteristiche specificate pi\u00f9 avanti).<\/p>\n<p style=\"text-align: justify;\"><strong>La prossima missione si svolger\u00e0 nel Sud di Minas Gerais, a Po\u00e7os de Caldas, nei giorni 10 e 11 ottobre 2018, presso l\u2019Agenzia Consolare Onoraria di Po\u00e7os de Caldas in Rua Piau\u00ed, 20, apto 1 \u2013 Centro con il seguente calendario<\/strong>:<\/p>\n<p>&#8211; Mercoled\u00ec, <strong>10 ottobre, dalle ore 15.00 alle ore 18.00<\/strong><\/p>\n<p>&#8211; Gioved\u00ec, <strong>11 ottobre, dalle ore 9.00 alle ore 12.00 e dalle ore 14.00 alle ore 17.00<\/strong><\/p>\n<p style=\"text-align: left;\">Per iscriversi all\u2019iniziativa, baster\u00e0 mandare una e-mail alla nostra Agenzia Consolare Onoraria all\u2019indirizzo pocosdecaldas.onorario@esteri.it, compilando, a seconda dell\u2019et\u00e0 del\/la richiedente, il modulo per maggiorenni o quello per minorenni.<\/p>\n<p style=\"text-align: justify;\">Chiaramente, potranno essere accettate solo le domande di chi ha regolarmente attualizzato la posizione anagrafica (ad esempio presentando a questo Consolato i propri eventuali atti di matrimonio, di divorzio, nascita di figli, etc.).<\/p>\n<p style=\"text-align: justify;\">Documenti da presentare il giorno della convocazione:<\/p>\n<p><span style=\"text-decoration: underline;\"><strong>A. Maggiorenni SENZA figli minori<\/strong><\/span><\/p>\n<p>1. <a href=\"resource\/doc\/2018\/08\/a_-_itinerante_-_domanda_passaporto_adulto.doc\">Modulo<\/a>\u00a0di richiesta compilato che dovr\u00e0 essere firmato in presenza dell\u2019addetto;<\/p>\n<p>2.\u00a0Due fotografie uguali, recenti, senza data, a colori, frontali e con sfondo bianco di 45mm di altezza per 35mm di larghezza;<\/p>\n<p>3. Documento d\u2019identit\u00e0 originale del richiedente (passaporto italiano, RNE, passaporto brasiliano valido o RG rilasciato da meno di 10 anni) pi\u00f9 fotocopia semplice fronte e retro. <strong>Non si accettano tesserini professionali n\u00e9 patenti<\/strong>;<\/p>\n<p>4. Prova di residenza a nome del richiedente, originale, recente (meno di 3 mesi) pi\u00f9 fotocopia semplice;<\/p>\n<p>5. Busta preaffrancata per \u201ccarta registrada\u201d formato 20&#215;18,5, plastificata, con francobollo di A\/R.<\/p>\n<p><span style=\"text-decoration: underline;\"><strong>B. Maggiorenni CON figli minori <\/strong><\/span><\/p>\n<p>1. <strong>Presenza dell\u2019altro genitore<\/strong> dei propri figli minori munito di documento di identit\u00e0 in originale e una copia (passaporto brasiliano valido o RG recente);<\/p>\n<p>2. <a href=\"resource\/doc\/2018\/08\/a_-_itinerante_-_domanda_passaporto_adulto.doc\"> Modulo<\/a> di richiesta compilato che dovr\u00e0 essere firmato in presenza dell\u2019addetto;<\/p>\n<p>3.\u00a0Due fotografie uguali, recenti, senza data, a colori, frontali e con sfondo bianco di 45mm di altezza per 35mm di larghezza;<\/p>\n<p>4. Documento d\u2019identit\u00e0 originale del richiedente (passaporto italiano, RNE, passaporto brasiliano valido o RG rilasciato da meno di 10 anni) pi\u00f9 fotocopia semplice fronte e retro. <strong>Non si accettano tesserini professionali n\u00e9 patenti<\/strong>;<\/p>\n<p>5. Prova di residenza a nome del richiedente, originale, recente (meno di 3 mesi) pi\u00f9 fotocopia semplice;<\/p>\n<p>6. Busta preaffrancata per \u201ccarta registrada\u201d formato 20&#215;18,5, plastificata, con francobollo di A\/R<\/p>\n<p><span style=\"text-decoration: underline;\"><strong>C. Minorenni<\/strong><\/span><\/p>\n<p>1. <strong>E\u2019 indispensabile la presenza di ambedue i genitori e del minore<\/strong>;<\/p>\n<p>2. <a href=\"resource\/doc\/2018\/08\/b_-_itinerante_-_domanda_passaporto_minore.doc\">Modulo<\/a>\u00a0di richiesta (minorenni) compilato e sottoscritto da entrambi i genitori in presenza dell\u2019addetto;<\/p>\n<p>3. Due fotografie uguali, recenti, senza data, a colori, frontali e con sfondo bianco di 45mm di altezza per 35mm di larghezza;<\/p>\n<p>4. <strong>Documenti d\u2019identit\u00e0 originali del minore e dei genitori<\/strong> (passaporto italiano, RNE, passaporto brasiliano valido o RG rilasciato da meno di 10 anni) pi\u00f9 fotocopia semplice fronte e retro;<\/p>\n<p>5. Prova di residenza, in originale, a nome del genitore cittadino italiano, recente (meno di 3 mesi) pi\u00f9 fotocopia semplice;<\/p>\n<p>6. Busta preaffrancata per \u201ccarta registrada\u201d formato 20&#215;18,5, plastificata, con francobollo di A\/R.<\/p>\n<p>\u00a0<\/p>\n<p style=\"text-align: justify;\"><strong>Si informa che il pagamento della tassa consolare per il rilascio del passaporto sar\u00e0 subordinato al controllo della documentazione e <\/strong><strong>verr\u00e0 richiesto in un secondo momento, dopo gli opportuni controlli, pertanto \u00e8 importantissimo indicare nella domanda il proprio indirizzo mail.<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"Nel tentativo di agevolare coloro per cui \u00e8 pi\u00f9 difficoltoso raggiungere il Consolato a Belo Horizonte, continuiamo le missioni di un \u201cfunzionario itinerante\u201d, che raccoglier\u00e0 le impronte digitali dei cittadini e delle cittadine italiani\/e interessati a richiedere un libretto di passaporto. I libretti, stampati successivamente, saranno trasmessi via posta ai rispettivi titolari (previa consegna al [&hellip;]","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"tags":[],"class_list":["post-1096","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/consbelohorizonte.esteri.it\/it\/wp-json\/wp\/v2\/posts\/1096","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/consbelohorizonte.esteri.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/consbelohorizonte.esteri.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/consbelohorizonte.esteri.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/consbelohorizonte.esteri.it\/it\/wp-json\/wp\/v2\/comments?post=1096"}],"version-history":[{"count":0,"href":"https:\/\/consbelohorizonte.esteri.it\/it\/wp-json\/wp\/v2\/posts\/1096\/revisions"}],"wp:attachment":[{"href":"https:\/\/consbelohorizonte.esteri.it\/it\/wp-json\/wp\/v2\/media?parent=1096"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/consbelohorizonte.esteri.it\/it\/wp-json\/wp\/v2\/tags?post=1096"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}